{"id":60,"count":3,"description":"","link":"https:\/\/blogs.glowscotland.org.uk\/wl\/digitallearningteam\/category\/digital-schools-award\/","name":"Digital Schools Award","slug":"digital-schools-award","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/digitallearningteam\/wp-json\/wp\/v2\/categories\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/digitallearningteam\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/digitallearningteam\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/digitallearningteam\/wp-json\/wp\/v2\/posts?categories=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}