{"id":9303,"date":"2025-02-05T13:27:25","date_gmt":"2025-02-05T12:27:25","guid":{"rendered":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/?p=9303"},"modified":"2025-02-05T13:27:25","modified_gmt":"2025-02-05T12:27:25","slug":"boccia-curling-festival","status":"publish","type":"post","link":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/","title":{"rendered":"Boccia &amp; Curling Festival"},"content":{"rendered":"<p>Last week 3 of our pupils attended the ASN Boccia and Curling Festival run by Active Schools with the college students at West Lothian College.<\/p>\n<p>We took part in lots of different stations to develop our throwing and rolling skills, and had lots of fun!<\/p>\n<div data-carousel-extra='{&quot;blog_id&quot;:24,&quot;permalink&quot;:&quot;https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/&quot;}' id='gallery-1' class='gallery galleryid-9303 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4421\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9304\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4421\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738145921&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4421\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132247\/IMG_4421-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4433\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9305\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4433\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738146732&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4433\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132251\/IMG_4433-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4451\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9306\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4451\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738147608&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4451\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132255\/IMG_4451-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4458-2\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9307\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4458-2\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738148351&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4458\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132259\/IMG_4458-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4445\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9308\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4445\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738147276&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4445\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132351\/IMG_4445-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4460\/'><img decoding=\"async\" width=\"474\" height=\"354\" src=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-1024x765.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-1024x765.jpg 1024w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-300x224.jpg 300w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-768x574.jpg 768w, https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460.jpg 1260w\" sizes=\"(max-width: 474px) 100vw, 474px\" data-attachment-id=\"9309\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/2025\/02\/05\/boccia-curling-festival\/img_4460\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460.jpg\" data-orig-size=\"1260,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1738148519&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4460\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-300x224.jpg\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/wl\/public\/beatlieblog\/uploads\/sites\/24\/2025\/02\/05132442\/IMG_4460-1024x765.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Last week 3 of our pupils attended the ASN Boccia and Curling Festival run by Active Schools with the college students at West Lothian College. We took part in lots of different stations to develop our throwing and rolling skills, and had lots of fun! &nbsp; &nbsp;<\/p>\n","protected":false},"author":8602,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[11262,11191,11245,11],"class_list":["post-9303","post","type-post","status-publish","format-standard","hentry","category-whole-school","tag-article-15-we-have-the-right-to-meet-with-other-children","tag-my-education-helps-me-to-develop-my-talents-to-the-full-uncrc-article-29","tag-article-31-we-have-the-right-to-play","tag-health-and-wellbeing"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/posts\/9303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/users\/8602"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/comments?post=9303"}],"version-history":[{"count":1,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/posts\/9303\/revisions"}],"predecessor-version":[{"id":9310,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/posts\/9303\/revisions\/9310"}],"wp:attachment":[{"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/media?parent=9303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/categories?post=9303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/wl\/beatlieblog\/wp-json\/wp\/v2\/tags?post=9303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}