{"id":2007,"date":"2024-05-14T13:37:08","date_gmt":"2024-05-14T13:37:08","guid":{"rendered":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/files\/2024\/05\/stem-badge.png"},"modified":"2024-05-14T13:37:08","modified_gmt":"2024-05-14T13:37:08","slug":"stem-badge","status":"inherit","type":"attachment","link":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/head-teachers-address\/stem-badge\/","title":{"rendered":"stem badge"},"author":6983,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2007","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png'><img decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-300x130.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-300x130.png 300w, https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-768x333.png 768w, https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png 794w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"2007\" data-permalink=\"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/head-teachers-address\/stem-badge\/\" data-orig-file=\"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png\" data-orig-size=\"794,344\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"stem badge\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-300x130.png\" data-large-file=\"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":794,"height":344,"file":"2024\/05\/stem-badge.png","sizes":{"medium":{"file":"stem-badge-300x130.png","width":300,"height":130,"filesize":23055,"mime_type":"image\/png","source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-300x130.png"},"thumbnail":{"file":"stem-badge-150x150.png","width":150,"height":150,"filesize":12499,"mime_type":"image\/png","source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-150x150.png"},"medium_large":{"file":"stem-badge-768x333.png","width":768,"height":333,"filesize":60038,"mime_type":"image\/png","source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-768x333.png"},"post-thumbnail":{"file":"stem-badge-672x344.png","width":672,"height":344,"filesize":11177,"mime_type":"image\/png","source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge-672x344.png"},"full":{"file":"stem-badge.png","width":794,"height":344,"mime_type":"image\/png","source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":391,"source_url":"https:\/\/blogs.glowscotland.org.uk\/re\/public\/newmains\/uploads\/sites\/2301\/2024\/05\/14133709\/stem-badge.png","_links":{"self":[{"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/media\/2007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/users\/6983"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/comments?post=2007"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":391,"href":"https:\/\/blogs.glowscotland.org.uk\/re\/newmains\/wp-json\/wp\/v2\/pages\/391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}